{"id":225133,"date":"2025-04-21T12:51:41","date_gmt":"2025-04-21T18:51:41","guid":{"rendered":"https:\/\/www.enteratever.com\/2023\/?p=225133"},"modified":"2025-04-21T12:51:41","modified_gmt":"2025-04-21T18:51:41","slug":"proponen-de-tres-a-diez-anos-de-prision-a-quien-sin-autorizacion-acceda-a-un-sistema-de-informatica-o-datos-protegidos","status":"publish","type":"post","link":"https:\/\/www.enteratever.com\/2023\/2025\/04\/21\/proponen-de-tres-a-diez-anos-de-prision-a-quien-sin-autorizacion-acceda-a-un-sistema-de-informatica-o-datos-protegidos\/","title":{"rendered":"Proponen de tres a diez a\u00f1os de prisi\u00f3n a quien sin autorizaci\u00f3n acceda a un sistema de inform\u00e1tica o datos protegidos"},"content":{"rendered":"<p>Visitas: 5<\/p><p>El diputado V\u00edctor Manuel P\u00e9rez D\u00edaz (PAN) impulsa una iniciativa de reforma al art\u00edculo 211 Bis 1 del C\u00f3digo Penal Federal, para que se sancione de tres a diez a\u00f1os de prisi\u00f3n y multa de hasta mil Unidades de Medida y Actualizaci\u00f3n, a quien sin autorizaci\u00f3n acceda a un sistema de inform\u00e1tica o datos protegidos por alg\u00fan mecanismo de seguridad, con el fin de sustraer, modificar, destruir, copiar o alterar informaci\u00f3n.<\/p>\n<p>La iniciativa, enviada a la Comisi\u00f3n de Justicia, plantea endurecer las penas a quienes ejecuten ese delito, y establece que cuando sea cometido para causar un da\u00f1o psicol\u00f3gico o material a la v\u00edctima, la pena ser\u00e1 aumentada en una tercera parte. <\/p>\n<p>El legislador argumenta que el phishing, el ransomware y las violaciones de la seguridad de los datos son ejemplos de las actuales ciberamenazas, donde los ciberdelincuentes son cada vez m\u00e1s \u00e1giles y mejor organizados, as\u00ed como el modo en que adaptan sus ataques y cooperan entre s\u00ed.<\/p>\n<p>En este sentido, indica que de acuerdo con la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana los principales delitos cibern\u00e9ticos son la extracci\u00f3n de datos sin consentimiento (hacking), ataques intencionados a sistemas operativos y software (cracking), forma de enga\u00f1o para obtener informaci\u00f3n bancaria (phishing), mensajes digitales con ligas de internet falsas al correo digital (spamming) y extorsi\u00f3n digital (ciberterrorismo).<\/p>\n<p>Considera que, si bien el Gobierno Federal ha realizado acciones encaminadas al combate de los delitos cibern\u00e9ticos, para lo cual se han creado distintas polic\u00edas cibern\u00e9ticas, tanto federales como locales, el Poder Legislativo debe dotar de marcos legales eficientes en el combate de este il\u00edcito.<\/p>\n<p>El diputado subraya que, al endurecer las penas por los delitos cibern\u00e9ticos, la delincuencia se encontrar\u00e1 ante un sistema que realmente castiga estas acciones y se abstendr\u00e1 de realizarlas, ya que en la actualidad la penalidad es muy baja &#8211;de seis meses a dos a\u00f1os de prisi\u00f3n y de cien a trescientos d\u00edas multa&#8211; y pueden salir f\u00e1cilmente bajo fianza o cauci\u00f3n.<\/p>\n<p> Enfatiza que un aumento significativo en las penalidades generar\u00e1 una baja significativa en estos delitos, ya que la delincuencia no ver\u00e1 estas actividades como un modo de generar ganancias y no salir perjudicada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visitas: 5El diputado V\u00edctor Manuel P\u00e9rez D\u00edaz (PAN) impulsa una iniciativa de reforma al art\u00edculo 211 Bis 1 del C\u00f3digo Penal Federal, para que se sancione de tres a diez a\u00f1os de prisi\u00f3n y multa de hasta mil Unidades de Medida y Actualizaci\u00f3n, a quien sin autorizaci\u00f3n acceda a un sistema de inform\u00e1tica o datos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":225134,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[252],"tags":[],"class_list":["post-225133","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales"],"nelio_content":{"isAutoShareEnabled":true,"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"followers":[7,2],"suggestedReferences":[],"efiUrl":"","efiAlt":"","highlights":[],"permalinkQueryArgs":[],"series":[]},"_links":{"self":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/225133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/comments?post=225133"}],"version-history":[{"count":1,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/225133\/revisions"}],"predecessor-version":[{"id":225139,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/225133\/revisions\/225139"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/media\/225134"}],"wp:attachment":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/media?parent=225133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/categories?post=225133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/tags?post=225133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}