{"id":224946,"date":"2025-04-14T13:24:29","date_gmt":"2025-04-14T19:24:29","guid":{"rendered":"https:\/\/www.enteratever.com\/2023\/?p=224946"},"modified":"2025-04-14T13:24:29","modified_gmt":"2025-04-14T19:24:29","slug":"mexico-busca-negociar-reduccion-de-aranceles-en-sectores-automotriz-de-acero-y-aluminio","status":"publish","type":"post","link":"https:\/\/www.enteratever.com\/2023\/2025\/04\/14\/mexico-busca-negociar-reduccion-de-aranceles-en-sectores-automotriz-de-acero-y-aluminio\/","title":{"rendered":"M\u00e9xico busca negociar reducci\u00f3n de aranceles en sectores automotriz, de acero y aluminio"},"content":{"rendered":"<p>Visitas: 6<\/p><p>La presidenta de M\u00e9xico, Claudia Sheinbaum, asegur\u00f3 este lunes que su Gobierno busca negociar una reducci\u00f3n en materia de aranceles con el Gobierno de Estados Unidos, en los sectores automotriz, de acero y aluminio.<\/p>\n<p>\u201cNo quisiera mencionar todas las propuestas que estamos haciendo a Estados Unidos, vamos a esperar algunos d\u00edas\u2026 Obviamente es una disminuci\u00f3n importante (lo que se propone)\u201d, apunt\u00f3 la mandataria durante su conferencia de prensa matutina.<\/p>\n<p>La gobernante mexicana se\u00f1al\u00f3 adem\u00e1s que actualmente hay una \u201ccomunicaci\u00f3n permanente\u201d del secretario de Econom\u00eda, Marcelo Ebrad, con el secretario de Comercio estadounidense, Howard Lutnick \u201cy ah\u00ed se est\u00e1 viendo todo este proceso\u201d.<\/p>\n<p>Record\u00f3 que lo publicado por el Gobierno de Estados Unidos es un arancel de 25 % a los veh\u00edculos completos, con un descuento de aquello que se fabrica en territorio estadounidense, mientras que en el caso de las autopartes el arancel para M\u00e9xico es todav\u00eda de cero.<\/p>\n<p>\u201cEn este momento no hay aranceles esperando que la Secretar\u00eda de Comercio o el Departamento de Comercio de los Estados Unidos ponga un arancel dependiendo del tipo de autoparte. Entonces, hasta ahora eso es lo que tenemos\u201d, enfatiz\u00f3.<\/p>\n<p>Se\u00f1al\u00f3 adem\u00e1s, que lo que su Gobierno est\u00e1 buscando es \u201cnegociar en acero y aluminio\u201d una rebaja en los aranceles.<\/p>\n<p>Trump anunci\u00f3 en febrero que castigar\u00eda a M\u00e9xico y Canad\u00e1 -por considerar que no hacen lo suficiente contra la migraci\u00f3n irregular y el tr\u00e1fico de fentanilo- con un arancel del 25 %, aunque congel\u00f3 en marzo la aplicaci\u00f3n de este impuesto aduanero sobre los bienes incluidos en el tratado comercial de EE.UU. sellado en 2020 con sus dos vecinos (T-MEC).<\/p>\n<p>Cuando el pasado 2 de abril Trump anunci\u00f3 lo que llam\u00f3 \u201caranceles rec\u00edprocos\u201d que implicaron tasas generalizadas del 10 % y unos vol\u00famenes superiores para otras regiones y pa\u00edses -como China o la Uni\u00f3n Europea (UE)- que exportan mucho a EE.UU., M\u00e9xico y Canad\u00e1 quedaron fuera de la lista de pa\u00edses castigados.<\/p>\n<p>XEU<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visitas: 6La presidenta de M\u00e9xico, Claudia Sheinbaum, asegur\u00f3 este lunes que su Gobierno busca negociar una reducci\u00f3n en materia de aranceles con el Gobierno de Estados Unidos, en los sectores automotriz, de acero y aluminio. \u201cNo quisiera mencionar todas las propuestas que estamos haciendo a Estados Unidos, vamos a esperar algunos d\u00edas\u2026 Obviamente es una [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":217999,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[252],"tags":[],"class_list":["post-224946","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales"],"nelio_content":{"isAutoShareEnabled":true,"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"followers":[7,2],"suggestedReferences":[],"efiUrl":"","efiAlt":"","highlights":[],"permalinkQueryArgs":[],"series":[]},"_links":{"self":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/224946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/comments?post=224946"}],"version-history":[{"count":2,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/224946\/revisions"}],"predecessor-version":[{"id":224948,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/224946\/revisions\/224948"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/media\/217999"}],"wp:attachment":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/media?parent=224946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/categories?post=224946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/tags?post=224946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}