{"id":224649,"date":"2025-04-07T09:03:55","date_gmt":"2025-04-07T15:03:55","guid":{"rendered":"https:\/\/www.enteratever.com\/2023\/?p=224649"},"modified":"2025-04-07T09:03:55","modified_gmt":"2025-04-07T15:03:55","slug":"impulsan-iniciativa-que-obliga-al-estado-a-visibilizar-el-papel-de-las-mujeres-en-archivos-historicos-y-bibliotecas-publicas","status":"publish","type":"post","link":"https:\/\/www.enteratever.com\/2023\/2025\/04\/07\/impulsan-iniciativa-que-obliga-al-estado-a-visibilizar-el-papel-de-las-mujeres-en-archivos-historicos-y-bibliotecas-publicas\/","title":{"rendered":"Impulsan iniciativa que obliga al Estado a visibilizar el papel de las mujeres en archivos hist\u00f3ricos y bibliotecas p\u00fablicas"},"content":{"rendered":"<p>Visitas: 10<\/p><p>La diputada Alma Lidia De La Vega S\u00e1nchez (Morena) plante\u00f3 que la pol\u00edtica cultural del Estado tenga la obligaci\u00f3n de revisar, actualizar y adecuar peri\u00f3dicamente las exposiciones permanentes, los textos museogr\u00e1ficos y los contenidos oficiales de museos, archivos hist\u00f3ricos y bibliotecas p\u00fablicas con perspectiva de g\u00e9nero e interseccionalidad.<\/p>\n<p>Lo anterior, para visibilizar el papel de las mujeres, de los pueblos originarios y de otros grupos de atenci\u00f3n prioritaria, promoviendo una cultura m\u00e1s inclusiva. <\/p>\n<p>Los cambios propuestos a los art\u00edculos 5, 6, 7, 12, 15 y 37 de la Ley General de Cultura y Derechos Culturales proponen que la Federaci\u00f3n, las entidades, los municipios y las alcald\u00edas de la Ciudad de M\u00e9xico apliquen medidas que garanticen la adecuaci\u00f3n de las exposiciones, acervos y materiales de museos, archivos hist\u00f3ricos y bibliotecas p\u00fablicas con perspectiva de g\u00e9nero e interseccionalidad, en coordinaci\u00f3n con especialistas y organizaciones de la sociedad civil en la materia.<\/p>\n<p>Asimismo, en el desarrollo de acciones para investigar, conservar, proteger, fomentar, formar, enriquecer y difundir el patrimonio cultural inmaterial, se deber\u00e1 garantizar que los contenidos hist\u00f3ricos y culturales reflejen la diversidad de la sociedad mexicana, incluyendo el reconocimiento de las aportaciones de mujeres, pueblos originarios y otros grupos de atenci\u00f3n prioritaria.<\/p>\n<p>Se precisa que se deber\u00e1 garantizar la consulta y participaci\u00f3n de organizaciones y especialistas en materia de g\u00e9nero e interseccionalidad en los procesos de revisi\u00f3n, adecuaci\u00f3n y actualizaci\u00f3n de los contenidos culturales de museos, archivos y bibliotecas p\u00fablicas.<\/p>\n<p>El documento, turnado a la Comisi\u00f3n de Cultura y Cinematograf\u00eda para su estudio, subraya que en M\u00e9xico los espacios culturales &#8211;museos, archivos hist\u00f3ricos y bibliotecas&#8211; han sido construidos desde narrativas hegem\u00f3nicas que tradicionalmente han invisibilizado o minimizado las aportaciones hist\u00f3ricas, sociales y culturales de las mujeres, pueblos originarios y otros grupos de atenci\u00f3n prioritaria. <\/p>\n<p>Esta situaci\u00f3n, agrega, perpet\u00faa una brecha de desigualdad y afecta el pleno ejercicio de los derechos culturales al reproducir discursos que excluyen la diversidad de la sociedad mexicana y no reflejan el principio de equidad e inclusi\u00f3n que deber\u00eda regir la pol\u00edtica cultural del Estado. <\/p>\n<p>La falta de una representaci\u00f3n incluyente no solo perpet\u00faa la desigualdad sino que limita el desarrollo de una cultura de derechos humanos; por ello, establecer la obligaci\u00f3n legal de actualizar los contenidos culturales no solo fortalece la pol\u00edtica, sino que garantiza la construcci\u00f3n de una memoria colectiva m\u00e1s justa y equitativa.<\/p>\n<p>Aclara que la aprobaci\u00f3n de la presente iniciativa no implicar\u00eda la creaci\u00f3n de nuevas unidades administrativas, ni plazas en la administraci\u00f3n p\u00fablica, ni nuevas instituciones o programas de gasto, por lo que no requiere ampliaciones presupuestarias. <\/p>\n<p>&#8211;ooOoo&#8211;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visitas: 10La diputada Alma Lidia De La Vega S\u00e1nchez (Morena) plante\u00f3 que la pol\u00edtica cultural del Estado tenga la obligaci\u00f3n de revisar, actualizar y adecuar peri\u00f3dicamente las exposiciones permanentes, los textos museogr\u00e1ficos y los contenidos oficiales de museos, archivos hist\u00f3ricos y bibliotecas p\u00fablicas con perspectiva de g\u00e9nero e interseccionalidad. Lo anterior, para visibilizar el papel [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":224650,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[252],"tags":[],"class_list":["post-224649","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales"],"nelio_content":{"isAutoShareEnabled":true,"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"followers":[7,2],"suggestedReferences":[],"efiUrl":"","efiAlt":"","highlights":[],"permalinkQueryArgs":[],"series":[]},"_links":{"self":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/224649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/comments?post=224649"}],"version-history":[{"count":1,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/224649\/revisions"}],"predecessor-version":[{"id":224651,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/224649\/revisions\/224651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/media\/224650"}],"wp:attachment":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/media?parent=224649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/categories?post=224649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/tags?post=224649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}