{"id":224600,"date":"2025-04-04T14:02:49","date_gmt":"2025-04-04T20:02:49","guid":{"rendered":"https:\/\/www.enteratever.com\/2023\/?p=224600"},"modified":"2025-04-04T14:02:49","modified_gmt":"2025-04-04T20:02:49","slug":"en-coatzacoalcos-refuerzan-la-prevencion-de-conductas-antisociales-en-jovenes","status":"publish","type":"post","link":"https:\/\/www.enteratever.com\/2023\/2025\/04\/04\/en-coatzacoalcos-refuerzan-la-prevencion-de-conductas-antisociales-en-jovenes\/","title":{"rendered":"En Coatzacoalcos refuerzan la prevenci\u00f3n de conductas antisociales en j\u00f3venes"},"content":{"rendered":"<p>Visitas: 2<\/p><p>Con el objetivo de concientizar a los j\u00f3venes sobre la prevenci\u00f3n de conductas antisociales y el uso responsable de las redes sociales, el Gobierno de Coatzacoalcos, a trav\u00e9s de la Direcci\u00f3n de Educaci\u00f3n, encabezada por Adriana Yolanda Garc\u00eda Garay, y la Direcci\u00f3n Municipal de la Juventud, a cargo de Jocelyn L\u00f3pez Rivera, llev\u00f3 a cabo una serie de pl\u00e1ticas en el Instituto La Salle del Sureste.<\/p>\n<p>Esta iniciativa cont\u00f3 con la participaci\u00f3n de la Coordinaci\u00f3n para la Prevenci\u00f3n y Atenci\u00f3n a las Adicciones (COPACA) y el Centro Estatal de Prevenci\u00f3n Social de la Violencia y la Delincuencia con Participaci\u00f3n Ciudadana (CEPREVIDE), quienes abordaron temas fundamentales como la prevenci\u00f3n del uso y abuso de sustancias adictivas y el impacto de las redes sociales en la conducta de los adolescentes.<\/p>\n<p>Como parte de la din\u00e1mica, se realiz\u00f3 una activaci\u00f3n f\u00edsica para fomentar la integraci\u00f3n y generar un ambiente de confianza entre los estudiantes.<\/p>\n<p>Asimismo, los j\u00f3venes participaron activamente en un intercambio de ideas y reflexiones sobre los temas abordados, recibiendo premios por su participaci\u00f3n.<\/p>\n<p>El gobierno de Coatzacoalcos reafirma su compromiso de seguir trabajando en coordinaci\u00f3n con las instancias especializadas en esos temas para impulsar la educaci\u00f3n y el bienestar de la juventud, promoviendo espacios de aprendizaje y prevenci\u00f3n en beneficio de la comunidad estudiantil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visitas: 2Con el objetivo de concientizar a los j\u00f3venes sobre la prevenci\u00f3n de conductas antisociales y el uso responsable de las redes sociales, el Gobierno de Coatzacoalcos, a trav\u00e9s de la Direcci\u00f3n de Educaci\u00f3n, encabezada por Adriana Yolanda Garc\u00eda Garay, y la Direcci\u00f3n Municipal de la Juventud, a cargo de Jocelyn L\u00f3pez Rivera, llev\u00f3 a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":224601,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[252],"tags":[],"class_list":["post-224600","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales"],"nelio_content":{"isAutoShareEnabled":true,"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"followers":[7,2],"suggestedReferences":[],"efiUrl":"","efiAlt":"","highlights":[],"permalinkQueryArgs":[],"series":[]},"_links":{"self":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/224600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/comments?post=224600"}],"version-history":[{"count":1,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/224600\/revisions"}],"predecessor-version":[{"id":224602,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/224600\/revisions\/224602"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/media\/224601"}],"wp:attachment":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/media?parent=224600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/categories?post=224600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/tags?post=224600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}