{"id":206105,"date":"2024-02-29T13:35:42","date_gmt":"2024-02-29T19:35:42","guid":{"rendered":"https:\/\/www.enteratever.com\/2023\/?p=206105"},"modified":"2024-02-29T13:35:44","modified_gmt":"2024-02-29T19:35:44","slug":"transformacion-de-la-calle-nardo-una-realidad","status":"publish","type":"post","link":"https:\/\/www.enteratever.com\/2023\/2024\/02\/29\/transformacion-de-la-calle-nardo-una-realidad\/","title":{"rendered":"Transformaci\u00f3n de la calle Nardo, una realidad"},"content":{"rendered":"<p>Visitas: 1<\/p>\n<p class=\"wp-block-paragraph\">Nanchital, Ver. \u2013 Lo que para los vecinos de la calle Nardo en la colonia Manuel Ram\u00edrez Romero era un sue\u00f1o, hoy es una realidad luego de m\u00e1s de 14 a\u00f1os de espera, gracias a la preocupaci\u00f3n y ocupaci\u00f3n de la Alcaldesa Esmeralda Mora Zamudio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese sector, se realiz\u00f3 la rehabilitaci\u00f3n de drenaje sanitario y agua potable, incluyendo la edificaci\u00f3n de guarniciones, banquetas y pavimentaci\u00f3n con concreto hidr\u00e1ulico, transformando as\u00ed esa v\u00eda de comunicaci\u00f3n que anteriormente era de dif\u00edcil acceso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy, las familias vecinas pueden circular caminando o en veh\u00edculo por dicha arteria, ubicada entre las calles Filigrana y Nuevo Le\u00f3n, a la par de tener un mejor acceso a servicios b\u00e1sicos y mayor plusval\u00eda a sus predios, aumento a sus condiciones de vida, lo que ayuda a seguir cimentando las bases de la transformaci\u00f3n en Nanchital.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visitas: 1 Nanchital, Ver. \u2013 Lo que para los vecinos de la calle Nardo en la colonia Manuel Ram\u00edrez Romero era un sue\u00f1o, hoy es una realidad luego de m\u00e1s de 14 a\u00f1os de espera, gracias a la preocupaci\u00f3n y ocupaci\u00f3n de la Alcaldesa Esmeralda Mora Zamudio. En ese sector, se realiz\u00f3 la rehabilitaci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":206107,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[258,241],"tags":[],"class_list":["post-206105","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nanchital","category-zona-sur"],"nelio_content":{"isAutoShareEnabled":true,"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"followers":[],"suggestedReferences":[],"efiUrl":"","efiAlt":"","highlights":[],"permalinkQueryArgs":[],"series":[]},"_links":{"self":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/206105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/comments?post=206105"}],"version-history":[{"count":1,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/206105\/revisions"}],"predecessor-version":[{"id":206109,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/206105\/revisions\/206109"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/media\/206107"}],"wp:attachment":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/media?parent=206105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/categories?post=206105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/tags?post=206105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}