{"id":193068,"date":"2023-06-14T11:47:38","date_gmt":"2023-06-14T17:47:38","guid":{"rendered":"https:\/\/www.enteratever.com\/2023\/?p=193068"},"modified":"2023-06-14T11:47:40","modified_gmt":"2023-06-14T17:47:40","slug":"por-trabajos-de-mantenimiento-de-cfe-ayuntamiento-de-coatzintla-suspendera-labores","status":"publish","type":"post","link":"https:\/\/www.enteratever.com\/2023\/2023\/06\/14\/por-trabajos-de-mantenimiento-de-cfe-ayuntamiento-de-coatzintla-suspendera-labores\/","title":{"rendered":"Por trabajos de mantenimiento de CFE Ayuntamiento de Coatzintla suspender\u00e1 labores."},"content":{"rendered":"<p>Visitas: 438<\/p>\n<p>Como parte de los trabajos de mantenimiento en las l\u00edneas que la Comisi\u00f3n Federal de Electricidad (CFE) se encuentra realizando, el Ayuntamiento de Coatzintla estar\u00e1 suspendiendo labores el pr\u00f3ximo jueves 15 de junio, esto debido a que contaran el suministro de energ\u00eda en esta zona de la ciudad.<\/p>\n\n\n\n<p>Los trabajos estar\u00e1n iniciando este mi\u00e9rcoles 14 de junio, por lo que en algunos sectores de la cabecera municipal se mantendr\u00e1n sin el servicio de energ\u00eda el\u00e9ctrica, por lo que la CFE ha hecho un llamado a la ciudadan\u00eda, para que tengan paciencia, pues con est\u00e1n trabajando lo m\u00e1s r\u00e1pido posible para que el suministro se reactive<\/p>\n\n\n\n<p>Las colonias en donde se estar\u00e1n realizando los trabajos durante los dos d\u00edas son la colonia Ruiz Cortines , Azteca , Sector Coatzintla y parte de Barrio de Xico en horario de 9:00 am. A 2:30 pm, en el que suspender\u00e1n el servicio para dar mantenimiento de l\u00edneas de la dependencia de energ\u00eda el\u00e9ctrica.<\/p>\n\n\n\n<p>Por lo que solo ser\u00e1n algunas calles y colonias donde se suspender\u00e1 el servicio de energ\u00eda durante esos d\u00edas , por lo que exhortan a tomar las medidas correspondientes mientras se regulariza el servicio de energ\u00eda el\u00e9ctrica, pues recordaron que es importante que realicen las revisiones necesarias para evitar cortos circuitos.<\/p>\n\n\n\n<p>Por esta raz\u00f3n el Ayuntamiento anunci\u00f3 a la ciudadan\u00eda de los trabajos que la CFE estar\u00e1 realizando en el municipio, adem\u00e1s de la suspensi\u00f3n de labores por la falta de energ\u00eda el\u00e9ctrica, las cuales se estar\u00e1n reactivando el d\u00eda viernes 16 de junio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visitas: 438 Como parte de los trabajos de mantenimiento en las l\u00edneas que la Comisi\u00f3n Federal de Electricidad (CFE) se encuentra realizando, el Ayuntamiento de Coatzintla estar\u00e1 suspendiendo labores el pr\u00f3ximo jueves 15 de junio, esto debido a que contaran el suministro de energ\u00eda en esta zona de la ciudad. Los trabajos estar\u00e1n iniciando este [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":193069,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[216,219],"tags":[41],"class_list":{"0":"post-193068","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-coatzintla","8":"category-zona-norte","9":"tag-portada"},"nelio_content":{"isAutoShareEnabled":true,"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"followers":[],"suggestedReferences":[],"efiUrl":"","efiAlt":"","highlights":[],"permalinkQueryArgs":[],"series":[]},"_links":{"self":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/193068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/comments?post=193068"}],"version-history":[{"count":1,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/193068\/revisions"}],"predecessor-version":[{"id":193071,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/193068\/revisions\/193071"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/media\/193069"}],"wp:attachment":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/media?parent=193068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/categories?post=193068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/tags?post=193068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}