{"id":178734,"date":"2021-03-31T20:17:38","date_gmt":"2021-03-31T20:17:38","guid":{"rendered":"https:\/\/www.enteratever.com\/2023\/incrementan-los-robos-a-viviendas-durante-periodo-vacacional\/"},"modified":"2021-03-31T20:17:38","modified_gmt":"2021-03-31T20:17:38","slug":"incrementan-los-robos-a-viviendas-durante-periodo-vacacional","status":"publish","type":"post","link":"https:\/\/www.enteratever.com\/2023\/2021\/03\/31\/incrementan-los-robos-a-viviendas-durante-periodo-vacacional\/","title":{"rendered":"Incrementan los robos a viviendas durante periodo vacacional"},"content":{"rendered":"<p>Visitas: 0<\/p>\n<p class=\"wp-block-paragraph\">Es durante el per\u00edodo vacacional es cuando suele registrase un aumento de robos a casa\/habitaci\u00f3n en colonias y avenidas de alta circulaci\u00f3n en esta ciudad, sin embargo, debido a las restricciones sanitarias para estas vacaciones, se espera que la incidencia baje.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con Aar\u00f3n Betanzos Zumaya, Director de la Polic\u00eda Municipal inform\u00f3 que las principales zonas donde se registran los robos a comercios y a viviendas son: el centro de la ciudad y avenidas de mayor afluencia peatonal, comercial y vehicular como: la Independencia, y sectores entre las que destacan la Camacho, Santa Emilia y Petromex.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se\u00f1al\u00f3 que como todos los a\u00f1os estos sectores son donde se tiene el mayor n\u00famero de robos, por lo que durante los periodos vacacionales es donde se realizan un mayor trabajo de vigilancia, esto para reducir el n\u00famero de robos a los hogares.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/www.enteratever.com\/2020\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-31-at-13.37.22.jpeg\" alt=\"\" data-id=\"41353\" data-full-url=\"https:\/\/www.enteratever.com\/2020\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-31-at-13.37.22.jpeg\" data-link=\"https:\/\/www.enteratever.com\/?attachment_id=41353\" class=\"wp-image-41353\"\/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Al igual durante las vacaciones los elementos de la polic\u00eda ofrecer\u00e1n orientaci\u00f3n tur\u00edstica a los ciudadanos, pero tambi\u00e9n atender\u00e1n puntualmente los llamados de emergencia que se realicen al 911, por lo que asegur\u00f3 que estar\u00e1n trabajo en coordinaci\u00f3n con las diferentes organizaciones par brindar mejor seguridad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recomend\u00f3 a los ciudadanos discreci\u00f3n con los planes vacacionales, no revelar los periodos en los que la familia estar\u00e1 ausente o el destino al que se dirige a desconocidos o personas que no sean de entera confianza, as\u00ed como la instalaci\u00f3n y actualizaci\u00f3n de dispositivos de seguridad, dar mantenimiento a chapas, alarmas, detectores de movimiento y otras protecciones para garantizar su buen funcionamiento, o bien instalar las que hagan falta, adem\u00e1s de solicitar vigilancia a personas de confianza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visitas: 0 Es durante el per\u00edodo vacacional es cuando suele registrase un aumento de robos a casa\/habitaci\u00f3n en colonias y avenidas de alta circulaci\u00f3n en esta ciudad, sin embargo, debido a las restricciones sanitarias para estas vacaciones, se espera que la incidencia baje. De acuerdo con Aar\u00f3n Betanzos Zumaya, Director de la Polic\u00eda Municipal inform\u00f3 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":178735,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[215],"tags":[],"class_list":["post-178734","post","type-post","status-publish","format-standard","has-post-thumbnail","category-papantla"],"nelio_content":{"isAutoShareEnabled":true,"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"followers":[],"suggestedReferences":[],"efiUrl":"","efiAlt":"","highlights":[],"permalinkQueryArgs":[],"series":[]},"_links":{"self":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/178734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/comments?post=178734"}],"version-history":[{"count":0,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/178734\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/media\/178735"}],"wp:attachment":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/media?parent=178734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/categories?post=178734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/tags?post=178734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}