{"id":169820,"date":"2014-04-18T02:57:54","date_gmt":"2014-04-18T02:57:54","guid":{"rendered":"https:\/\/www.enteratever.com\/2023\/campana-de-concientizacion-de-conductor-designado-bebidas-alcoholicas\/"},"modified":"2014-04-18T02:57:54","modified_gmt":"2014-04-18T02:57:54","slug":"campana-de-concientizacion-de-conductor-designado-bebidas-alcoholicas","status":"publish","type":"post","link":"https:\/\/www.enteratever.com\/2023\/2014\/04\/18\/campana-de-concientizacion-de-conductor-designado-bebidas-alcoholicas\/","title":{"rendered":"Campa\u00f1a de concientizaci\u00f3n de conductor designado bebidas alcoholicas"},"content":{"rendered":"<p>Visitas: 0<\/p><figure id=\"attachment_49885\" aria-describedby=\"caption-attachment-49885\" style=\"width: 660px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.enteratever.com\/wp-content\/uploads\/2014\/04\/IMG_2209.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-49885\" alt=\"Campa\u00f1a de concientizaci\u00f3n de conductor designado bebidas alcoholicas\" src=\"http:\/\/www.enteratever.com\/wp-content\/uploads\/2014\/04\/IMG_2209.jpg\" width=\"660\" height=\"440\" \/><\/a><figcaption id=\"caption-attachment-49885\" class=\"wp-caption-text\">Campa\u00f1a de concientizaci\u00f3n de conductor designado bebidas alcoholicas<\/figcaption><\/figure>\n<p style=\"text-align: justify\">Por: Jazm\u00edn Morales<\/p>\n<p style=\"text-align: justify\">Para evitar accidentes en las carreteras de la regi\u00f3n, autoridades municipales y empresa cervecera realizan una campa\u00f1a contra de que conductores ingieran bebidas alcoh\u00f3licas.<!--more--><\/p>\n<p style=\"text-align: justify\">As\u00ed lo anunci\u00f3 el el Secretario de Desarrollo Econ\u00f3mico del Ayuntamiento de Poza Rica, Antonio Herrera quien manifest\u00f3 que este Viernes Santo se realizar\u00e1 una campa\u00f1a a la altura de la distribuidora de cervecer\u00eda Cuauht\u00e9moc- Moctezuma, para entregar kits promocionales a los conductores que circulen por la carretera Poza Rica- Cazones.<\/p>\n<p style=\"text-align: justify\">La idea es, dijo, crear conciencia entre los conductores que se abstengan de ingerir bebidas alcoh\u00f3licas si van a manejar y de esa manera se eviten accidentes. Ser\u00e1n diez j\u00f3venes los que estar\u00e1n apoyando a las autoridades municipales y a la empresa en esta campa\u00f1a que iniciar\u00e1 a las diez horas y concluir\u00e1 a mediod\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visitas: 0Por: Jazm\u00edn Morales Para evitar accidentes en las carreteras de la regi\u00f3n, autoridades municipales y empresa cervecera realizan una campa\u00f1a contra de que conductores ingieran bebidas alcoh\u00f3licas.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[213],"tags":[],"class_list":["post-169820","post","type-post","status-publish","format-standard","category-poza-rica"],"nelio_content":{"isAutoShareEnabled":true,"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"followers":[],"suggestedReferences":[],"efiUrl":"","efiAlt":"","highlights":[],"permalinkQueryArgs":[],"series":[]},"_links":{"self":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/169820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/comments?post=169820"}],"version-history":[{"count":0,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/169820\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/media?parent=169820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/categories?post=169820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/tags?post=169820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}