{"id":169814,"date":"2014-04-17T16:49:19","date_gmt":"2014-04-17T16:49:19","guid":{"rendered":"https:\/\/www.enteratever.com\/2023\/desalojan-oficinas-de-solidaridad\/"},"modified":"2014-04-17T16:49:19","modified_gmt":"2014-04-17T16:49:19","slug":"desalojan-oficinas-de-solidaridad","status":"publish","type":"post","link":"https:\/\/www.enteratever.com\/2023\/2014\/04\/17\/desalojan-oficinas-de-solidaridad\/","title":{"rendered":"Se lleva el perro, el gato y el rat\u00f3n H\u00e9ctor Cruz"},"content":{"rendered":"<p>Visitas: 1<\/p><figure id=\"attachment_49677\" aria-describedby=\"caption-attachment-49677\" style=\"width: 587px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.enteratever.com\/wp-content\/uploads\/2014\/04\/IMG-20140417-WA0000.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-49677\" alt=\"Desalojan oficinas de Solidaridad\" src=\"http:\/\/www.enteratever.com\/wp-content\/uploads\/2014\/04\/IMG-20140417-WA0000.jpg\" width=\"587\" height=\"440\" \/><\/a><figcaption id=\"caption-attachment-49677\" class=\"wp-caption-text\">Desalojan oficinas de Solidaridad<\/figcaption><\/figure>\n<p style=\"text-align: justify\">Kattia Vera<\/p>\n<p style=\"text-align: justify\">Desde las 10 de la ma\u00f1ana del jueves, empleados de H\u00e9ctor Cruz Comenzaron a sacar muebles y papeler\u00eda de las oficinas de Solidaridad sin que se sepan los motivos por los cuales se realiza esta acci\u00f3n.<!--more--><\/p>\n<p style=\"text-align: justify\">Un sujeto que seg\u00fan testigos es hijo de H\u00e9ctor Cruz lanz\u00f3 chorros de agua en contra de los reporteros gr\u00e1ficos que registraban los hechos, mientras que un adulto mayor tomaba fotograf\u00edas a los periodistas.<\/p>\n<p style=\"text-align: justify\">El desalojo de las oficinas se da luego de que un uez ordenara a H\u00e9ctor Cruz que convoque a asamblea de socios para que explique el quebranto de al menos 800 millones de pesos de la caja de la asociaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visitas: 1Kattia Vera Desde las 10 de la ma\u00f1ana del jueves, empleados de H\u00e9ctor Cruz Comenzaron a sacar muebles y papeler\u00eda de las oficinas de Solidaridad sin que se sepan los motivos por los cuales se realiza esta acci\u00f3n.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[213],"tags":[],"class_list":["post-169814","post","type-post","status-publish","format-standard","category-poza-rica"],"nelio_content":{"isAutoShareEnabled":true,"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"followers":[],"suggestedReferences":[],"efiUrl":"","efiAlt":"","highlights":[],"permalinkQueryArgs":[],"series":[]},"_links":{"self":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/169814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/comments?post=169814"}],"version-history":[{"count":0,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/169814\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/media?parent=169814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/categories?post=169814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/tags?post=169814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}