{"id":168275,"date":"2018-03-23T17:50:48","date_gmt":"2018-03-23T17:50:48","guid":{"rendered":"https:\/\/www.enteratever.com\/2023\/feria-infantil-no-te-quemes-en-tihuatlan\/"},"modified":"2018-03-23T17:50:48","modified_gmt":"2018-03-23T17:50:48","slug":"feria-infantil-no-te-quemes-en-tihuatlan","status":"publish","type":"post","link":"https:\/\/www.enteratever.com\/2023\/2018\/03\/23\/feria-infantil-no-te-quemes-en-tihuatlan\/","title":{"rendered":"Feria infantil \u00abNo te quemes\u00bb en Tihuatl\u00e1n"},"content":{"rendered":"<p>Visitas: 1<\/p><p style=\"text-align: justify;\"><strong>Por Jaqueline Hern\u00e1ndez | Enteratever.com<\/strong><\/p>\n<p style=\"text-align: justify;\">Se llevar\u00e1 a cabo la feria infantil \u00abNo te quemes\u00bbde la fundaci\u00f3n Michou y Mau en el municipio de Tihuatl\u00e1n, la cual tiene como objetivo promover la cultura preventiva y brindar asistencia a ni\u00f1os quemados.<\/p>\n<p style=\"text-align: justify;\">Dicho evento esta programado para el d\u00eda 11 de abril, sin embargo, aun no se define en donde ser\u00e1 instalada la feria, las opciones que han sido consideradas son la unidad deportiva \u00abFrancisco Ortiz Yorio\u00bb o la explanada del Ayuntamiento municipal.<\/p>\n<p style=\"text-align: justify;\">La fundaci\u00f3n Michou y Mau es una organizaci\u00f3n no lucrativa con mas 18 a\u00f1os de experiencia en dar asistencia integral a ni\u00f1os con quemaduras severas y a sus familias.<\/p>\n<p style=\"text-align: justify;\">Por esta raz\u00f3n, en coordinaci\u00f3n con la Secretaria de Protecci\u00f3n Civil y la Direcci\u00f3n General de Capacitaci\u00f3n y Adiestramiento, es como fue creada esta feria, la cual ser\u00e1 instalada en diferentes lugares de la regi\u00f3n como Poza Rica, Tuxpan, Coatzintla y Tihuatl\u00e1n.<\/p>\n<p style=\"text-align: justify;\">De igual manera se colocara en varias ciudades de la rep\u00fablica como la ciudad de M\u00e9xico, Veracruz, Boca del Rio, entre otros.<\/p>\n<p style=\"text-align: justify;\">En el municipio de Tihuatl\u00e1n se espera atender a 60 ni\u00f1os por hora, ya que se estar\u00e1n realizando una variedad de actividades para complementar la informaci\u00f3n que la fundaci\u00f3n Michou y Mau espera compartir en esta feria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visitas: 1Por Jaqueline Hern\u00e1ndez | Enteratever.com Se llevar\u00e1 a cabo la feria infantil \u00abNo te quemes\u00bbde la fundaci\u00f3n Michou y Mau en el municipio de Tihuatl\u00e1n, la cual tiene como objetivo promover la cultura preventiva y brindar asistencia a ni\u00f1os quemados. Dicho evento esta programado para el d\u00eda 11 de abril, sin embargo, aun no [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":168276,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[217],"tags":[],"class_list":["post-168275","post","type-post","status-publish","format-standard","has-post-thumbnail","category-tihuatlan"],"nelio_content":{"isAutoShareEnabled":true,"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"followers":[],"suggestedReferences":[],"efiUrl":"","efiAlt":"","highlights":[],"permalinkQueryArgs":[],"series":[]},"_links":{"self":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/168275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/comments?post=168275"}],"version-history":[{"count":0,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/168275\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/media\/168276"}],"wp:attachment":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/media?parent=168275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/categories?post=168275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/tags?post=168275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}