{"id":168223,"date":"2018-02-28T18:41:09","date_gmt":"2018-02-28T18:41:09","guid":{"rendered":"https:\/\/www.enteratever.com\/2023\/prospera-dara-de-baja-a-familias-que-tengan-doble-beneficios-en-tihuatlan\/"},"modified":"2018-02-28T18:41:09","modified_gmt":"2018-02-28T18:41:09","slug":"prospera-dara-de-baja-a-familias-que-tengan-doble-beneficios-en-tihuatlan","status":"publish","type":"post","link":"https:\/\/www.enteratever.com\/2023\/2018\/02\/28\/prospera-dara-de-baja-a-familias-que-tengan-doble-beneficios-en-tihuatlan\/","title":{"rendered":"Enga\u00f1os e intimidaci\u00f3n de retirar apoyos de Prospera puede tener tintes pol\u00edticos"},"content":{"rendered":"<p>Visitas: 1<\/p><p style=\"text-align: justify;\"><strong>Por: Jaqueline Hern\u00e1ndez | Enteratever.com<\/strong><\/p>\n<p>Desmienten que el programa del Gobierno Federal Prospera pueda retirar apoyos a las personas que les ser\u00e1 otorgado el programa \u201cVeracruz comienza Contigo\u201d, las reglas de operaci\u00f3n no estipulan que se le pueda quitar el apoyo por recibir apoyos alimentarios del Gobierno del Estado.<\/p>\n<p style=\"text-align: justify;\">Cesar Mancha Alarc\u00f3n, Delegado regional del programa \u201cVeracruz comienza Contigo\u201d asegur\u00f3 \u201cProspera solo est\u00e1 enga\u00f1ando e intimidando a la gente al decirles que van a ser dados de baja de su programa si se quieren integrar al nuestro, lo cual es injusto, ya que los \u00fanicos que est\u00e1n siendo perjudicados son las familias de escasos recursos\u201d, mencion\u00f3.<\/p>\n<p style=\"text-align: justify;\">Esto es una mentira, ya que las reglas de operaci\u00f3n de Prospera no dice que por recibir apoyos de alimentaci\u00f3n del Gobierno del Estado van a causar la baja de su programa, recalc\u00f3 que esta situaci\u00f3n puede tener fines pol\u00edticos.<\/p>\n<p style=\"text-align: justify;\">\u201cNosotros somos Sedesol del Estado y ellos Sedesol Federal, cada uno tenemos nuestras reglas de operaci\u00f3n y nuestros propios programas, no s\u00e9 si realmente lo hagan ellos con ciertos fines pol\u00edticos, ya que las personas perjudicadas son nuestras familias veracruzanas de escasos recursos y ellos no tienen la culpa, porque tenemos que beneficiarlas a todas por parejo\u201d, se\u00f1al\u00f3.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, el Delegado coment\u00f3 que esto ha provocado las quejas de esta familia ante esta situaci\u00f3n, ya que las familias de escasos recursos necesitan apoyos de parte del gobierno independientemente de que partido pol\u00edtico o gobernante sea.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>*Prospera miente, no puede dar de baja a los que reciben el programa \u201cVeracruz comienza Contigo\u201d<\/p>\n","protected":false},"author":2,"featured_media":168224,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[217],"tags":[],"class_list":["post-168223","post","type-post","status-publish","format-standard","has-post-thumbnail","category-tihuatlan"],"nelio_content":{"isAutoShareEnabled":true,"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"followers":[],"suggestedReferences":[],"efiUrl":"","efiAlt":"","highlights":[],"permalinkQueryArgs":[],"series":[]},"_links":{"self":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/168223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/comments?post=168223"}],"version-history":[{"count":0,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/168223\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/media\/168224"}],"wp:attachment":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/media?parent=168223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/categories?post=168223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/tags?post=168223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}