{"id":168187,"date":"2018-02-13T18:40:34","date_gmt":"2018-02-13T18:40:34","guid":{"rendered":"https:\/\/www.enteratever.com\/2023\/entregan-lentes-gratuitos-en-tihuatlan\/"},"modified":"2018-02-13T18:40:34","modified_gmt":"2018-02-13T18:40:34","slug":"entregan-lentes-gratuitos-en-tihuatlan","status":"publish","type":"post","link":"https:\/\/www.enteratever.com\/2023\/2018\/02\/13\/entregan-lentes-gratuitos-en-tihuatlan\/","title":{"rendered":"Entregan lentes gratuitos en Tihuatl\u00e1n"},"content":{"rendered":"<p>Visitas: 3<\/p><p style=\"text-align: justify;\"><strong>Por Jaqueline Hern\u00e1ndez | Enteratever.com<\/strong><\/p>\n<p style=\"text-align: justify;\">Como muestra de apoyo hac\u00eda los ni\u00f1os, j\u00f3venes y adultos m\u00e1s vulnerables del municipio de Tihuatl\u00e1n y sus comunidades, se llev\u00f3 a cabo la entrega de 20 lentes gratuitos, los cuales fueron otorgados por Carmen Cervantes, Presidenta del Sistema Municipal del Desarrollo Integral de la Familia (DIF).<\/p>\n<p style=\"text-align: justify;\">La presidenta afirm\u00f3 que fue un d\u00eda muy importante, ya que se logr\u00f3 arrancar con el programa que lleva como nombre \u201cVer bien es m\u00e1s que mirar\u201d, y esto es gracias al apoyo que ha recibido el DIF por parte del alcalde Ra\u00fal Hern\u00e1ndez Gallardo.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, aprovech\u00f3 para mencionar que la cl\u00ednica DIF ha tenido muy buenos comentarios, por lo que se est\u00e1 buscando ampliar los servicios para que la cl\u00ednica contin\u00fae creciendo y brindando apoyo a m\u00e1s personas.<\/p>\n<p style=\"text-align: justify;\">\u201cEl d\u00eda de ayer 12 de febrero ya se implement\u00f3 el servicio de ultrasonido y el estudio de laboratorio, pero tambi\u00e9n necesitamos otra sala de urgencias, as\u00ed que de igual manera esperamos pronto poder ampliar la cl\u00ednica\u201d, asegur\u00f3.<\/p>\n<p style=\"text-align: justify;\">Tambi\u00e9n coment\u00f3 que se van a retomar proyectos de la administraci\u00f3n pasada como Apadrinando \u00c1ngeles y DIF m\u00e1s cerca de ti, ya que su compromiso es trabajar paso a paso m\u00e1s cerca de las personas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visitas: 3Por Jaqueline Hern\u00e1ndez | Enteratever.com Como muestra de apoyo hac\u00eda los ni\u00f1os, j\u00f3venes y adultos m\u00e1s vulnerables del municipio de Tihuatl\u00e1n y sus comunidades, se llev\u00f3 a cabo la entrega de 20 lentes gratuitos, los cuales fueron otorgados por Carmen Cervantes, Presidenta del Sistema Municipal del Desarrollo Integral de la Familia (DIF). La presidenta [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":168188,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[217],"tags":[],"class_list":["post-168187","post","type-post","status-publish","format-standard","has-post-thumbnail","category-tihuatlan"],"nelio_content":{"isAutoShareEnabled":true,"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"followers":[],"suggestedReferences":[],"efiUrl":"","efiAlt":"","highlights":[],"permalinkQueryArgs":[],"series":[]},"_links":{"self":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/168187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/comments?post=168187"}],"version-history":[{"count":0,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/168187\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/media\/168188"}],"wp:attachment":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/media?parent=168187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/categories?post=168187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/tags?post=168187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}