{"id":168181,"date":"2018-02-09T20:42:50","date_gmt":"2018-02-09T20:42:50","guid":{"rendered":"https:\/\/www.enteratever.com\/2023\/se-extiende-hasta-marzo-el-pago-de-predial-en-tihuatlan\/"},"modified":"2018-02-09T20:42:50","modified_gmt":"2018-02-09T20:42:50","slug":"se-extiende-hasta-marzo-el-pago-de-predial-en-tihuatlan","status":"publish","type":"post","link":"https:\/\/www.enteratever.com\/2023\/2018\/02\/09\/se-extiende-hasta-marzo-el-pago-de-predial-en-tihuatlan\/","title":{"rendered":"Se extiende hasta marzo el pago de predial en Tihuatl\u00e1n"},"content":{"rendered":"<p>Visitas: 2<\/p><p style=\"text-align: justify;\"><strong>Por: Jaqueline Hern\u00e1ndez | Enteratever.com<\/strong><\/p>\n<p style=\"text-align: justify;\">Se extiende hasta el 31 de marzo el pago de impuesto predial 2018 en el municipio de Tihuatl\u00e1n, hasta el momento solo ha sido cubierto el pago del 31% de los predios, pero se espera que en los pr\u00f3ximos d\u00edas m\u00e1s personas se acerquen a hacer su pago.<\/p>\n<p style=\"text-align: justify;\">\u201cEs importante que la gente venga a realizar el pago del predial, ya que con eso nos ayudan a crear m\u00e1s acciones en beneficio de los m\u00e1s vulnerables\u201d, mencion\u00f3 Rosa Marina S\u00e1nchez L\u00f3pez, Tesorera municipal.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, se\u00f1al\u00f3 que el padr\u00f3n factura que deben alcanzar es de 9 millones 84 mil 147 pesos, pero que en el corte del mes de enero solo se logr\u00f3 obtener 2 millones 477 mil 88 pesos, lo que representa un 27%.<\/p>\n<p style=\"text-align: justify;\">Para que esto sea posible deben ser cubiertos 19 mil 552 prediales, de los cuales solo se han pagado 6 mil 110 predios, lo que representa un 31%, por lo que esperan que m\u00e1s gente se acerque a realizar su pago para que se puede alcanzar el padr\u00f3n factura, asegur\u00f3.<\/p>\n<p>Por \u00faltimo, la tesorera dijo que la promoci\u00f3n del 20% de descuento al p\u00fablico general y del 50% a pensionados y jubilados continuara hasta marzo, adem\u00e1s de que al hacer el pago van a poder participar en la rifa de una camioneta \u00faltimo modelo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visitas: 2Por: Jaqueline Hern\u00e1ndez | Enteratever.com Se extiende hasta el 31 de marzo el pago de impuesto predial 2018 en el municipio de Tihuatl\u00e1n, hasta el momento solo ha sido cubierto el pago del 31% de los predios, pero se espera que en los pr\u00f3ximos d\u00edas m\u00e1s personas se acerquen a hacer su pago. \u201cEs [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":168182,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[217],"tags":[],"class_list":["post-168181","post","type-post","status-publish","format-standard","has-post-thumbnail","category-tihuatlan"],"nelio_content":{"isAutoShareEnabled":true,"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"followers":[],"suggestedReferences":[],"efiUrl":"","efiAlt":"","highlights":[],"permalinkQueryArgs":[],"series":[]},"_links":{"self":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/168181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/comments?post=168181"}],"version-history":[{"count":0,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/168181\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/media\/168182"}],"wp:attachment":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/media?parent=168181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/categories?post=168181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/tags?post=168181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}