{"id":168163,"date":"2018-02-03T03:52:18","date_gmt":"2018-02-03T03:52:18","guid":{"rendered":"https:\/\/www.enteratever.com\/2023\/carnaval-de-tihuatlan-del-16-al-18-de-marzo\/"},"modified":"2018-02-03T03:52:18","modified_gmt":"2018-02-03T03:52:18","slug":"carnaval-de-tihuatlan-del-16-al-18-de-marzo","status":"publish","type":"post","link":"https:\/\/www.enteratever.com\/2023\/2018\/02\/03\/carnaval-de-tihuatlan-del-16-al-18-de-marzo\/","title":{"rendered":"Carnaval de Tihuatl\u00e1n del 16 al 18 de marzo"},"content":{"rendered":"<p>Visitas: 9<\/p><p style=\"text-align: justify;\"><strong>Por Jaqueline Hern\u00e1ndez | Enteratever.com<\/strong><\/p>\n<p style=\"text-align: justify;\">Las fechas para el Carnaval de Tihuatl\u00e1n han sido confirmadas, este se llevar\u00e1 a cabo los d\u00edas 16, 17 y 18 de marzo, posteriormente se estar\u00e1 celebrando el carnaval de la zona conurbada, el d\u00eda 24 de marzo, una semana despu\u00e9s que el del municipio.<\/p>\n<p style=\"text-align: justify;\">De igual manera, tambi\u00e9n ya fueron confirmados los artistas y grupos que van a estar presentes en estos dos carnavales. \u201cEl 16 vamos a contar con la coronaci\u00f3n de la reina y en el evento estar\u00e1 la Sonora Dinamita, el d\u00eda s\u00e1bado 17 de marzo estar\u00e1n los Caracoles, y en los recorridos de los carros aleg\u00f3ricos estar\u00e1 Adri\u00e1n Di Monte, el domingo estar\u00e1n los grupos musicales Impacto norte\u00f1o y Bronco, y Dorismar en recorridos\u201d, mencion\u00f3 Jorge Montiel, Director de Turismo.<\/p>\n<p style=\"text-align: justify;\">Mientras tanto, en la zona conurbada, en la que tambi\u00e9n se realiza el carnaval a\u00f1o con a\u00f1o, se estar\u00e1 presentando Bronco y algunos participantes del programa Enamor\u00e1ndonos.<\/p>\n<p style=\"text-align: justify;\">\u201cSomos un municipio en el que nuestro carnaval siempre ha sido un \u00e9xito, as\u00ed que esperamos que este a\u00f1o asista m\u00e1s gente de otros lugares, adem\u00e1s de las personas de las comunidades que cada a\u00f1o nos acompa\u00f1an, para que de esta forma puedan conocer las zonas tur\u00edsticas que tiene Tihuatl\u00e1n\u201d, agreg\u00f3 el director.<\/p>\n<p style=\"text-align: justify;\">Por esta raz\u00f3n, se\u00f1al\u00f3 que Ra\u00fal Hern\u00e1ndez Gallardo, Presidente municipal planea hacer una gran difusi\u00f3n para el Carnaval, esto con el objetivo m\u00e1s gente conozca el municipio.<\/p>\n<p>\u201cPor eso nos estamos organizando todos los departamentos que pueden apoyar en este Carnaval, as\u00ed podremos brindarles a los visitantes y ciudadanos de Tihuatl\u00e1n un gran evento como cada a\u00f1o\u201d, agreg\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visitas: 9Por Jaqueline Hern\u00e1ndez | Enteratever.com Las fechas para el Carnaval de Tihuatl\u00e1n han sido confirmadas, este se llevar\u00e1 a cabo los d\u00edas 16, 17 y 18 de marzo, posteriormente se estar\u00e1 celebrando el carnaval de la zona conurbada, el d\u00eda 24 de marzo, una semana despu\u00e9s que el del municipio. De igual manera, tambi\u00e9n [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":168164,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[217],"tags":[],"class_list":["post-168163","post","type-post","status-publish","format-standard","has-post-thumbnail","category-tihuatlan"],"nelio_content":{"isAutoShareEnabled":true,"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"followers":[],"suggestedReferences":[],"efiUrl":"","efiAlt":"","highlights":[],"permalinkQueryArgs":[],"series":[]},"_links":{"self":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/168163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/comments?post=168163"}],"version-history":[{"count":0,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/168163\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/media\/168164"}],"wp:attachment":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/media?parent=168163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/categories?post=168163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/tags?post=168163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}