{"id":168145,"date":"2018-01-25T20:33:30","date_gmt":"2018-01-25T20:33:30","guid":{"rendered":"https:\/\/www.enteratever.com\/2023\/prevalecen-bibliotecas-publicas-pese-a-tecnologias\/"},"modified":"2018-01-25T20:33:30","modified_gmt":"2018-01-25T20:33:30","slug":"prevalecen-bibliotecas-publicas-pese-a-tecnologias","status":"publish","type":"post","link":"https:\/\/www.enteratever.com\/2023\/2018\/01\/25\/prevalecen-bibliotecas-publicas-pese-a-tecnologias\/","title":{"rendered":"Prevalecen Bibliotecas P\u00fablicas pese a tecnolog\u00edas"},"content":{"rendered":"<p>Visitas: 1<\/p><p style=\"text-align: justify;\"><strong>Por: Jaqueline Hern\u00e1ndez | Enteratever.com<\/strong><\/p>\n<p style=\"text-align: justify;\">Las personas siguen haciendo uso de la biblioteca p\u00fablica a pesar de las tecnolog\u00edas , se\u00f1al\u00f3 Minerva Ju\u00e1rez Sosa, encargada de la Biblioteca p\u00fablica municipal Benito Ju\u00e1rez Garc\u00eda de Tihuatl\u00e1n.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, mencion\u00f3 que esto es gracias a que en las escuelas est\u00e1n impulsando a los ni\u00f1os y j\u00f3venes a que vuelvan a leer y que sus investigaciones las realicen en los libros y no solo con el Internet, ya deben buscar la manera de complementar estas dos herramientas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visitas: 1Por: Jaqueline Hern\u00e1ndez | Enteratever.com Las personas siguen haciendo uso de la biblioteca p\u00fablica a pesar de las tecnolog\u00edas , se\u00f1al\u00f3 Minerva Ju\u00e1rez Sosa, encargada de la Biblioteca p\u00fablica municipal Benito Ju\u00e1rez Garc\u00eda de Tihuatl\u00e1n. Adem\u00e1s, mencion\u00f3 que esto es gracias a que en las escuelas est\u00e1n impulsando a los ni\u00f1os y j\u00f3venes a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":168146,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[217],"tags":[],"class_list":["post-168145","post","type-post","status-publish","format-standard","has-post-thumbnail","category-tihuatlan"],"nelio_content":{"isAutoShareEnabled":true,"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"followers":[],"suggestedReferences":[],"efiUrl":"","efiAlt":"","highlights":[],"permalinkQueryArgs":[],"series":[]},"_links":{"self":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/168145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/comments?post=168145"}],"version-history":[{"count":0,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/168145\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/media\/168146"}],"wp:attachment":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/media?parent=168145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/categories?post=168145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/tags?post=168145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}