{"id":168139,"date":"2018-01-22T17:38:47","date_gmt":"2018-01-22T17:38:47","guid":{"rendered":"https:\/\/www.enteratever.com\/2023\/comuna-escucha-peticiones-de-los-ciudadanos-en-tihuatlan\/"},"modified":"2018-01-22T17:38:47","modified_gmt":"2018-01-22T17:38:47","slug":"comuna-escucha-peticiones-de-los-ciudadanos-en-tihuatlan","status":"publish","type":"post","link":"https:\/\/www.enteratever.com\/2023\/2018\/01\/22\/comuna-escucha-peticiones-de-los-ciudadanos-en-tihuatlan\/","title":{"rendered":"Comuna escucha peticiones de los ciudadanos en Tihuatl\u00e1n"},"content":{"rendered":"<p>Visitas: 1<\/p><p style=\"text-align: justify;\"><strong>Por Jaqueline Hern\u00e1ndez | Enteratever.com<\/strong><\/p>\n<p style=\"text-align: justify;\">Para conocer m\u00e1s de cerca los problemas de la ciudadan\u00eda se realiz\u00f3 en el municipio de Tihuatl\u00e1n mesas de \u201cAtenci\u00f3n Ciudadana\u201d por parte de Ra\u00fal Hern\u00e1ndez Gallardo, Presidente de Tihuatl\u00e1n y sus regidores para escuchar las peticiones de los ciudadanos que conforman las distintas comunidades del municipio de Tihuatl\u00e1n.<\/p>\n<p style=\"text-align: justify;\">Entre las principales peticiones que realizaron las personas est\u00e1n la pavimentaci\u00f3n de calles, la construcci\u00f3n de drenajes, el cumplimiento del servicio del agua, apoyos con materiales para las escuelas, entre otras.<\/p>\n<p style=\"text-align: justify;\">Cada uno de los regidores junto con el alcalde atendi\u00f3 a cientos de personas, las cuales se dieron cita desde las 7:30 de la ma\u00f1ana en el auditorio municipal Benito Ju\u00e1rez, esperando su turno para poder ser escuchadas.<\/p>\n<p style=\"text-align: justify;\">Algunos de estos ciudadanos lograron que sus necesidades fueran resueltas en ese momento, sin embargo, otros tendr\u00e1n que esperar una respuesta por parte del presidente municipal y su comuna.<\/p>\n<p style=\"text-align: justify;\">Esta es la tercera ocasi\u00f3n que se realiza la Atenci\u00f3n Ciudadana, todos los d\u00edas lunes se seguir\u00e1 realizando en el auditorio municipal Benito Ju\u00e1rez para que los ciudadanos puedan continuar haciendo sus peticiones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visitas: 1Por Jaqueline Hern\u00e1ndez | Enteratever.com Para conocer m\u00e1s de cerca los problemas de la ciudadan\u00eda se realiz\u00f3 en el municipio de Tihuatl\u00e1n mesas de \u201cAtenci\u00f3n Ciudadana\u201d por parte de Ra\u00fal Hern\u00e1ndez Gallardo, Presidente de Tihuatl\u00e1n y sus regidores para escuchar las peticiones de los ciudadanos que conforman las distintas comunidades del municipio de Tihuatl\u00e1n. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":168140,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[217],"tags":[],"class_list":["post-168139","post","type-post","status-publish","format-standard","has-post-thumbnail","category-tihuatlan"],"nelio_content":{"isAutoShareEnabled":true,"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"followers":[],"suggestedReferences":[],"efiUrl":"","efiAlt":"","highlights":[],"permalinkQueryArgs":[],"series":[]},"_links":{"self":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/168139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/comments?post=168139"}],"version-history":[{"count":0,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/posts\/168139\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/media\/168140"}],"wp:attachment":[{"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/media?parent=168139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/categories?post=168139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.enteratever.com\/2023\/wp-json\/wp\/v2\/tags?post=168139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}